﻿{"id":102689,"date":"2020-01-08T14:30:27","date_gmt":"2020-01-08T17:30:27","guid":{"rendered":"http:\/\/jornalperiscopio.com.br\/site\/?p=102689"},"modified":"2020-01-08T14:30:28","modified_gmt":"2020-01-08T17:30:28","slug":"suspeito-de-tentar-roubar-mulher-e-preso-na-rodovia-castello-branco","status":"publish","type":"post","link":"https:\/\/jornalperiscopio.com.br\/site\/suspeito-de-tentar-roubar-mulher-e-preso-na-rodovia-castello-branco\/","title":{"rendered":"Suspeito de tentar roubar mulher \u00e9 preso na Rodovia Castello Branco"},"content":{"rendered":"\n<p>Um\nhomem identificado como B.F.L., de 36 anos, foi preso na tarde do \u00faltimo domingo\n(05), suspeito de tentar roubar uma motorista de 55 anos no estacionamento de\num shopping na altura do Km 72 da Rodovia Castello Branco (SP-280), em Itu. <\/p>\n\n\n\n<p>De acordo com informa\u00e7\u00f5es, por volta das 15h10 a v\u00edtima se encontrava no estacionamento do centro de compras para sair com seu ve\u00edculo, um Hyundai\/HB20 prata, quando foi abordada pelo suspeito, que aparentando estar na posse da arma de fogo, teria amea\u00e7ado a motorista, anunciando o assalto e exigindo as chaves do carro.<\/p>\n\n\n\n<p>Assustada, a mulher reagiu empurrando B.F.L. e gritando, chamando assim a aten\u00e7\u00e3o dos seguran\u00e7as do estabelecimento que abordaram o suspeito, acionando a Pol\u00edcia Militar Rodovi\u00e1ria que em pouco tempo chegou ao local.<\/p>\n\n\n\n<p>Questionado, B.F.L. negou ter tentado roubar, alegando que havia acabado de sair de uma cl\u00ednica de recupera\u00e7\u00e3o para dependentes qu\u00edmicos, situada nas proximidades do shopping e que s\u00f3 estava ali para pedir dinheiro com o intuito de ir para casa, dizendo ainda que a mulher \u201cteria se assustado, por isso havia gritado\u201d.<\/p>\n\n\n\n<p>Em revista pessoal, foi encontrada em poder do suspeito uma escova para limpar sapatos, que o indiv\u00edduo teria utilizado para fingir estar na posse de arma de fogo. B.F.L. recebeu voz de pris\u00e3o sendo encaminhado ao Plant\u00e3o Policial da Delegacia Central, permanecendo \u00e0 disposi\u00e7\u00e3o da Justi\u00e7a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Indiv\u00edduo teria utilizado uma escova de limpar sapatos para fingir estar na posse de arma de fogo.<\/p>\n","protected":false},"author":7,"featured_media":76573,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[53,12],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Suspeito de tentar roubar mulher \u00e9 preso na Rodovia Castello Branco<\/title>\n<meta name=\"description\" content=\"Indiv\u00edduo teria utilizado uma escova de limpar sapatos para fingir estar na posse de arma de fogo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalperiscopio.com.br\/site\/suspeito-de-tentar-roubar-mulher-e-preso-na-rodovia-castello-branco\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Suspeito de tentar roubar mulher \u00e9 preso na Rodovia Castello Branco\" \/>\n<meta property=\"og:description\" content=\"Indiv\u00edduo teria utilizado uma escova de limpar sapatos para fingir estar na posse de arma de fogo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalperiscopio.com.br\/site\/suspeito-de-tentar-roubar-mulher-e-preso-na-rodovia-castello-branco\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal Perisc\u00f3pio | Jornal do Povo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornalperiscopioitu\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-08T17:30:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-08T17:30:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2017\/09\/sirene.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"455\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andr\u00e9 Roedel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andr\u00e9 Roedel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/suspeito-de-tentar-roubar-mulher-e-preso-na-rodovia-castello-branco\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/suspeito-de-tentar-roubar-mulher-e-preso-na-rodovia-castello-branco\/\"},\"author\":{\"name\":\"Andr\u00e9 Roedel\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/person\/3dae6b83a83e3a18e259f65640b2eb1f\"},\"headline\":\"Suspeito de tentar roubar mulher \u00e9 preso na Rodovia Castello Branco\",\"datePublished\":\"2020-01-08T17:30:27+00:00\",\"dateModified\":\"2020-01-08T17:30:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/suspeito-de-tentar-roubar-mulher-e-preso-na-rodovia-castello-branco\/\"},\"wordCount\":255,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#organization\"},\"articleSection\":[\"Not\u00edcias\",\"Pol\u00edcia\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/jornalperiscopio.com.br\/site\/suspeito-de-tentar-roubar-mulher-e-preso-na-rodovia-castello-branco\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/suspeito-de-tentar-roubar-mulher-e-preso-na-rodovia-castello-branco\/\",\"url\":\"https:\/\/jornalperiscopio.com.br\/site\/suspeito-de-tentar-roubar-mulher-e-preso-na-rodovia-castello-branco\/\",\"name\":\"Suspeito de tentar roubar mulher \u00e9 preso na Rodovia Castello Branco\",\"isPartOf\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#website\"},\"datePublished\":\"2020-01-08T17:30:27+00:00\",\"dateModified\":\"2020-01-08T17:30:28+00:00\",\"description\":\"Indiv\u00edduo teria utilizado uma escova de limpar sapatos para fingir estar na posse de arma de fogo.\",\"breadcrumb\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/suspeito-de-tentar-roubar-mulher-e-preso-na-rodovia-castello-branco\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/jornalperiscopio.com.br\/site\/suspeito-de-tentar-roubar-mulher-e-preso-na-rodovia-castello-branco\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/suspeito-de-tentar-roubar-mulher-e-preso-na-rodovia-castello-branco\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/jornalperiscopio.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Suspeito de tentar roubar mulher \u00e9 preso na Rodovia Castello Branco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#website\",\"url\":\"https:\/\/jornalperiscopio.com.br\/site\/\",\"name\":\"Jornal Perisc\u00f3pio | Jornal do Povo\",\"description\":\"Jornal Perisc\u00f3pio\",\"publisher\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/jornalperiscopio.com.br\/site\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#organization\",\"name\":\"Jornal Perisc\u00f3pio\",\"url\":\"https:\/\/jornalperiscopio.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2017\/01\/cropped-cropped-logo_Jornal_Periscopio-2.png\",\"contentUrl\":\"http:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2017\/01\/cropped-cropped-logo_Jornal_Periscopio-2.png\",\"width\":420,\"height\":106,\"caption\":\"Jornal Perisc\u00f3pio\"},\"image\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/jornalperiscopioitu\/\",\"http:\/\/www.instagram.com\/jornalperiscopio\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/person\/3dae6b83a83e3a18e259f65640b2eb1f\",\"name\":\"Andr\u00e9 Roedel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3a62a9ee5934bf7cd122a2cfa7a8b13a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3a62a9ee5934bf7cd122a2cfa7a8b13a?s=96&d=mm&r=g\",\"caption\":\"Andr\u00e9 Roedel\"},\"url\":\"https:\/\/jornalperiscopio.com.br\/site\/author\/andreroedel\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Suspeito de tentar roubar mulher \u00e9 preso na Rodovia Castello Branco","description":"Indiv\u00edduo teria utilizado uma escova de limpar sapatos para fingir estar na posse de arma de fogo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalperiscopio.com.br\/site\/suspeito-de-tentar-roubar-mulher-e-preso-na-rodovia-castello-branco\/","og_locale":"pt_BR","og_type":"article","og_title":"Suspeito de tentar roubar mulher \u00e9 preso na Rodovia Castello Branco","og_description":"Indiv\u00edduo teria utilizado uma escova de limpar sapatos para fingir estar na posse de arma de fogo.","og_url":"https:\/\/jornalperiscopio.com.br\/site\/suspeito-de-tentar-roubar-mulher-e-preso-na-rodovia-castello-branco\/","og_site_name":"Jornal Perisc\u00f3pio | Jornal do Povo","article_publisher":"https:\/\/www.facebook.com\/jornalperiscopioitu\/","article_published_time":"2020-01-08T17:30:27+00:00","article_modified_time":"2020-01-08T17:30:28+00:00","og_image":[{"width":800,"height":455,"url":"https:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2017\/09\/sirene.jpg","type":"image\/jpeg"}],"author":"Andr\u00e9 Roedel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Andr\u00e9 Roedel","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalperiscopio.com.br\/site\/suspeito-de-tentar-roubar-mulher-e-preso-na-rodovia-castello-branco\/#article","isPartOf":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/suspeito-de-tentar-roubar-mulher-e-preso-na-rodovia-castello-branco\/"},"author":{"name":"Andr\u00e9 Roedel","@id":"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/person\/3dae6b83a83e3a18e259f65640b2eb1f"},"headline":"Suspeito de tentar roubar mulher \u00e9 preso na Rodovia Castello Branco","datePublished":"2020-01-08T17:30:27+00:00","dateModified":"2020-01-08T17:30:28+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/suspeito-de-tentar-roubar-mulher-e-preso-na-rodovia-castello-branco\/"},"wordCount":255,"commentCount":0,"publisher":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/#organization"},"articleSection":["Not\u00edcias","Pol\u00edcia"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalperiscopio.com.br\/site\/suspeito-de-tentar-roubar-mulher-e-preso-na-rodovia-castello-branco\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalperiscopio.com.br\/site\/suspeito-de-tentar-roubar-mulher-e-preso-na-rodovia-castello-branco\/","url":"https:\/\/jornalperiscopio.com.br\/site\/suspeito-de-tentar-roubar-mulher-e-preso-na-rodovia-castello-branco\/","name":"Suspeito de tentar roubar mulher \u00e9 preso na Rodovia Castello Branco","isPartOf":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/#website"},"datePublished":"2020-01-08T17:30:27+00:00","dateModified":"2020-01-08T17:30:28+00:00","description":"Indiv\u00edduo teria utilizado uma escova de limpar sapatos para fingir estar na posse de arma de fogo.","breadcrumb":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/suspeito-de-tentar-roubar-mulher-e-preso-na-rodovia-castello-branco\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalperiscopio.com.br\/site\/suspeito-de-tentar-roubar-mulher-e-preso-na-rodovia-castello-branco\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/jornalperiscopio.com.br\/site\/suspeito-de-tentar-roubar-mulher-e-preso-na-rodovia-castello-branco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jornalperiscopio.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Suspeito de tentar roubar mulher \u00e9 preso na Rodovia Castello Branco"}]},{"@type":"WebSite","@id":"https:\/\/jornalperiscopio.com.br\/site\/#website","url":"https:\/\/jornalperiscopio.com.br\/site\/","name":"Jornal Perisc\u00f3pio | Jornal do Povo","description":"Jornal Perisc\u00f3pio","publisher":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornalperiscopio.com.br\/site\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jornalperiscopio.com.br\/site\/#organization","name":"Jornal Perisc\u00f3pio","url":"https:\/\/jornalperiscopio.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/logo\/image\/","url":"http:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2017\/01\/cropped-cropped-logo_Jornal_Periscopio-2.png","contentUrl":"http:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2017\/01\/cropped-cropped-logo_Jornal_Periscopio-2.png","width":420,"height":106,"caption":"Jornal Perisc\u00f3pio"},"image":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jornalperiscopioitu\/","http:\/\/www.instagram.com\/jornalperiscopio"]},{"@type":"Person","@id":"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/person\/3dae6b83a83e3a18e259f65640b2eb1f","name":"Andr\u00e9 Roedel","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3a62a9ee5934bf7cd122a2cfa7a8b13a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3a62a9ee5934bf7cd122a2cfa7a8b13a?s=96&d=mm&r=g","caption":"Andr\u00e9 Roedel"},"url":"https:\/\/jornalperiscopio.com.br\/site\/author\/andreroedel\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/posts\/102689"}],"collection":[{"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/comments?post=102689"}],"version-history":[{"count":1,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/posts\/102689\/revisions"}],"predecessor-version":[{"id":102690,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/posts\/102689\/revisions\/102690"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/media\/76573"}],"wp:attachment":[{"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/media?parent=102689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/categories?post=102689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/tags?post=102689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}