﻿{"id":133891,"date":"2023-08-31T18:09:35","date_gmt":"2023-08-31T21:09:35","guid":{"rendered":"http:\/\/jornalperiscopio.com.br\/site\/?p=133891"},"modified":"2023-08-31T18:09:37","modified_gmt":"2023-08-31T21:09:37","slug":"sensacao-do-momento-veigh-e-atracao-do-festival-urban-trap-em-sorocaba","status":"publish","type":"post","link":"https:\/\/jornalperiscopio.com.br\/site\/sensacao-do-momento-veigh-e-atracao-do-festival-urban-trap-em-sorocaba\/","title":{"rendered":"Sensa\u00e7\u00e3o do momento, Veigh \u00e9 atra\u00e7\u00e3o do festival \u201cUrban Trap\u201d, em Sorocaba"},"content":{"rendered":"\n<p>Dono da maior estreia nacional da hist\u00f3ria da plataforma Spotify, registrada em maio deste ano, a sensa\u00e7\u00e3o do momento, Veigh, \u00e9 uma das atra\u00e7\u00f5es do \u201cUrban Trap\u201d, festival de m\u00fasica que ser\u00e1 realizado no dia 23 de setembro, s\u00e1bado, no Te Vejo no Haras, em Sorocaba.<\/p>\n\n\n\n<p>Nascido e criado em Itapevi (SP), Veigh \u00e9 cantor e compositor do g\u00eanero trap, uma varia\u00e7\u00e3o do rap. Com voz forte e mel\u00f3dica, um beat eletr\u00f4nico grave e letras profundas sobre emo\u00e7\u00f5es e cr\u00edticas sociais, o artista come\u00e7ou sua carreira com seu amigo Heitor, no extinto duo Constela\u00e7\u00e3o.<\/p>\n\n\n\n<p>Para completar o line up do festival, MC Caverinha volta a se apresentar na cidade ap\u00f3s o grande sucesso na Festa Julina de Sorocaba, al\u00e9m de Marks, que faz show pela primeira vez na cidade, no \u201cUrban Trap\u201d.<\/p>\n\n\n\n<p>Os ingressos para o festival custam a partir de R$30 (pista \/ promocional) e come\u00e7am a ser vendidos a partir das 18h desta quinta-feira (31) atrav\u00e9s do site <a href=\"http:\/\/baladapp.com.br\">baladapp.com.br<\/a>. A classifica\u00e7\u00e3o et\u00e1ria \u00e9 16 anos. O Te Vejo no Haras fica na Estrada do Ferraz, s\/n, no Jardim Iporanga II. Mais informa\u00e7\u00f5es pelo telefone (15) 9 9138-3574.<\/p>\n\n\n\n<p><strong>Servi\u00e7o:<br><\/strong>Urban Trap \u2013 Veigh + MC Caverinha + Marks<br>Dia 23 de setembro, a partir das 16h<br>Local: Te Vejo no haras \u2013 Estrada do Ferraz, s\/n \u2013 Jd. Iporanga II<br>Ingressos: a partir de R$30 (pista \u2013 promocional)<br>Vendas a partir das 18h desta quinta-feira (31): <a href=\"http:\/\/baladapp.com.br\">baladapp.com.br<\/a><br>Classifica\u00e7\u00e3o et\u00e1ria: 16 anos<br>Mais informa\u00e7\u00f5es: (15) 9 9138-3574<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>MC Caverinha e Marks completam as atra\u00e7\u00f5es do evento, que ser\u00e1 em setembro.<\/p>\n","protected":false},"author":1,"featured_media":133892,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[166],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sensa\u00e7\u00e3o do momento, Veigh \u00e9 atra\u00e7\u00e3o do festival \u201cUrban Trap\u201d, em Sorocaba<\/title>\n<meta name=\"description\" content=\"MC Caverinha e Marks completam as atra\u00e7\u00f5es do evento, que ser\u00e1 em setembro.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalperiscopio.com.br\/site\/sensacao-do-momento-veigh-e-atracao-do-festival-urban-trap-em-sorocaba\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sensa\u00e7\u00e3o do momento, Veigh \u00e9 atra\u00e7\u00e3o do festival \u201cUrban Trap\u201d, em Sorocaba\" \/>\n<meta property=\"og:description\" content=\"MC Caverinha e Marks completam as atra\u00e7\u00f5es do evento, que ser\u00e1 em setembro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalperiscopio.com.br\/site\/sensacao-do-momento-veigh-e-atracao-do-festival-urban-trap-em-sorocaba\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal Perisc\u00f3pio | Jornal do Povo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornalperiscopioitu\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-31T21:09:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-31T21:09:37+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2023\/08\/veigh.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"675\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornal Perisc\u00f3pio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal Perisc\u00f3pio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/sensacao-do-momento-veigh-e-atracao-do-festival-urban-trap-em-sorocaba\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/sensacao-do-momento-veigh-e-atracao-do-festival-urban-trap-em-sorocaba\/\"},\"author\":{\"name\":\"Jornal Perisc\u00f3pio\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/person\/509eaa6e74ff99fb48058b4547d055d7\"},\"headline\":\"Sensa\u00e7\u00e3o do momento, Veigh \u00e9 atra\u00e7\u00e3o do festival \u201cUrban Trap\u201d, em Sorocaba\",\"datePublished\":\"2023-08-31T21:09:35+00:00\",\"dateModified\":\"2023-08-31T21:09:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/sensacao-do-momento-veigh-e-atracao-do-festival-urban-trap-em-sorocaba\/\"},\"wordCount\":266,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#organization\"},\"articleSection\":[\"Agenda\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/jornalperiscopio.com.br\/site\/sensacao-do-momento-veigh-e-atracao-do-festival-urban-trap-em-sorocaba\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/sensacao-do-momento-veigh-e-atracao-do-festival-urban-trap-em-sorocaba\/\",\"url\":\"https:\/\/jornalperiscopio.com.br\/site\/sensacao-do-momento-veigh-e-atracao-do-festival-urban-trap-em-sorocaba\/\",\"name\":\"Sensa\u00e7\u00e3o do momento, Veigh \u00e9 atra\u00e7\u00e3o do festival \u201cUrban Trap\u201d, em Sorocaba\",\"isPartOf\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#website\"},\"datePublished\":\"2023-08-31T21:09:35+00:00\",\"dateModified\":\"2023-08-31T21:09:37+00:00\",\"description\":\"MC Caverinha e Marks completam as atra\u00e7\u00f5es do evento, que ser\u00e1 em setembro.\",\"breadcrumb\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/sensacao-do-momento-veigh-e-atracao-do-festival-urban-trap-em-sorocaba\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/jornalperiscopio.com.br\/site\/sensacao-do-momento-veigh-e-atracao-do-festival-urban-trap-em-sorocaba\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/sensacao-do-momento-veigh-e-atracao-do-festival-urban-trap-em-sorocaba\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/jornalperiscopio.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sensa\u00e7\u00e3o do momento, Veigh \u00e9 atra\u00e7\u00e3o do festival \u201cUrban Trap\u201d, em Sorocaba\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#website\",\"url\":\"https:\/\/jornalperiscopio.com.br\/site\/\",\"name\":\"Jornal Perisc\u00f3pio | Jornal do Povo\",\"description\":\"Jornal Perisc\u00f3pio\",\"publisher\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/jornalperiscopio.com.br\/site\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#organization\",\"name\":\"Jornal Perisc\u00f3pio\",\"url\":\"https:\/\/jornalperiscopio.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2017\/01\/cropped-cropped-logo_Jornal_Periscopio-2.png\",\"contentUrl\":\"http:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2017\/01\/cropped-cropped-logo_Jornal_Periscopio-2.png\",\"width\":420,\"height\":106,\"caption\":\"Jornal Perisc\u00f3pio\"},\"image\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/jornalperiscopioitu\/\",\"http:\/\/www.instagram.com\/jornalperiscopio\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/person\/509eaa6e74ff99fb48058b4547d055d7\",\"name\":\"Jornal Perisc\u00f3pio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7fd60e6256514f9f6bac0d31eb9382e6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7fd60e6256514f9f6bac0d31eb9382e6?s=96&d=mm&r=g\",\"caption\":\"Jornal Perisc\u00f3pio\"},\"url\":\"https:\/\/jornalperiscopio.com.br\/site\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sensa\u00e7\u00e3o do momento, Veigh \u00e9 atra\u00e7\u00e3o do festival \u201cUrban Trap\u201d, em Sorocaba","description":"MC Caverinha e Marks completam as atra\u00e7\u00f5es do evento, que ser\u00e1 em setembro.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalperiscopio.com.br\/site\/sensacao-do-momento-veigh-e-atracao-do-festival-urban-trap-em-sorocaba\/","og_locale":"pt_BR","og_type":"article","og_title":"Sensa\u00e7\u00e3o do momento, Veigh \u00e9 atra\u00e7\u00e3o do festival \u201cUrban Trap\u201d, em Sorocaba","og_description":"MC Caverinha e Marks completam as atra\u00e7\u00f5es do evento, que ser\u00e1 em setembro.","og_url":"https:\/\/jornalperiscopio.com.br\/site\/sensacao-do-momento-veigh-e-atracao-do-festival-urban-trap-em-sorocaba\/","og_site_name":"Jornal Perisc\u00f3pio | Jornal do Povo","article_publisher":"https:\/\/www.facebook.com\/jornalperiscopioitu\/","article_published_time":"2023-08-31T21:09:35+00:00","article_modified_time":"2023-08-31T21:09:37+00:00","og_image":[{"width":675,"height":450,"url":"http:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2023\/08\/veigh.jpeg","type":"image\/jpeg"}],"author":"Jornal Perisc\u00f3pio","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jornal Perisc\u00f3pio","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalperiscopio.com.br\/site\/sensacao-do-momento-veigh-e-atracao-do-festival-urban-trap-em-sorocaba\/#article","isPartOf":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/sensacao-do-momento-veigh-e-atracao-do-festival-urban-trap-em-sorocaba\/"},"author":{"name":"Jornal Perisc\u00f3pio","@id":"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/person\/509eaa6e74ff99fb48058b4547d055d7"},"headline":"Sensa\u00e7\u00e3o do momento, Veigh \u00e9 atra\u00e7\u00e3o do festival \u201cUrban Trap\u201d, em Sorocaba","datePublished":"2023-08-31T21:09:35+00:00","dateModified":"2023-08-31T21:09:37+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/sensacao-do-momento-veigh-e-atracao-do-festival-urban-trap-em-sorocaba\/"},"wordCount":266,"commentCount":0,"publisher":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/#organization"},"articleSection":["Agenda"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalperiscopio.com.br\/site\/sensacao-do-momento-veigh-e-atracao-do-festival-urban-trap-em-sorocaba\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalperiscopio.com.br\/site\/sensacao-do-momento-veigh-e-atracao-do-festival-urban-trap-em-sorocaba\/","url":"https:\/\/jornalperiscopio.com.br\/site\/sensacao-do-momento-veigh-e-atracao-do-festival-urban-trap-em-sorocaba\/","name":"Sensa\u00e7\u00e3o do momento, Veigh \u00e9 atra\u00e7\u00e3o do festival \u201cUrban Trap\u201d, em Sorocaba","isPartOf":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/#website"},"datePublished":"2023-08-31T21:09:35+00:00","dateModified":"2023-08-31T21:09:37+00:00","description":"MC Caverinha e Marks completam as atra\u00e7\u00f5es do evento, que ser\u00e1 em setembro.","breadcrumb":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/sensacao-do-momento-veigh-e-atracao-do-festival-urban-trap-em-sorocaba\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalperiscopio.com.br\/site\/sensacao-do-momento-veigh-e-atracao-do-festival-urban-trap-em-sorocaba\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/jornalperiscopio.com.br\/site\/sensacao-do-momento-veigh-e-atracao-do-festival-urban-trap-em-sorocaba\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jornalperiscopio.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Sensa\u00e7\u00e3o do momento, Veigh \u00e9 atra\u00e7\u00e3o do festival \u201cUrban Trap\u201d, em Sorocaba"}]},{"@type":"WebSite","@id":"https:\/\/jornalperiscopio.com.br\/site\/#website","url":"https:\/\/jornalperiscopio.com.br\/site\/","name":"Jornal Perisc\u00f3pio | Jornal do Povo","description":"Jornal Perisc\u00f3pio","publisher":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornalperiscopio.com.br\/site\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jornalperiscopio.com.br\/site\/#organization","name":"Jornal Perisc\u00f3pio","url":"https:\/\/jornalperiscopio.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/logo\/image\/","url":"http:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2017\/01\/cropped-cropped-logo_Jornal_Periscopio-2.png","contentUrl":"http:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2017\/01\/cropped-cropped-logo_Jornal_Periscopio-2.png","width":420,"height":106,"caption":"Jornal Perisc\u00f3pio"},"image":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jornalperiscopioitu\/","http:\/\/www.instagram.com\/jornalperiscopio"]},{"@type":"Person","@id":"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/person\/509eaa6e74ff99fb48058b4547d055d7","name":"Jornal Perisc\u00f3pio","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7fd60e6256514f9f6bac0d31eb9382e6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7fd60e6256514f9f6bac0d31eb9382e6?s=96&d=mm&r=g","caption":"Jornal Perisc\u00f3pio"},"url":"https:\/\/jornalperiscopio.com.br\/site\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/posts\/133891"}],"collection":[{"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/comments?post=133891"}],"version-history":[{"count":1,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/posts\/133891\/revisions"}],"predecessor-version":[{"id":133893,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/posts\/133891\/revisions\/133893"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/media\/133892"}],"wp:attachment":[{"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/media?parent=133891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/categories?post=133891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/tags?post=133891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}