﻿{"id":133894,"date":"2023-08-31T18:10:33","date_gmt":"2023-08-31T21:10:33","guid":{"rendered":"http:\/\/jornalperiscopio.com.br\/site\/?p=133894"},"modified":"2023-08-31T18:10:50","modified_gmt":"2023-08-31T21:10:50","slug":"sambista-xande-de-pilares-anuncia-show-em-sorocaba","status":"publish","type":"post","link":"https:\/\/jornalperiscopio.com.br\/site\/sambista-xande-de-pilares-anuncia-show-em-sorocaba\/","title":{"rendered":"Sambista Xande de Pilares anuncia show em Sorocaba"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"720\" src=\"http:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2023\/08\/xande-pilares-1280x720-1.jpg\" alt=\"\" class=\"wp-image-133895\" srcset=\"https:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2023\/08\/xande-pilares-1280x720-1.jpg 1280w, https:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2023\/08\/xande-pilares-1280x720-1-700x394.jpg 700w, https:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2023\/08\/xande-pilares-1280x720-1-768x432.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/figure>\n\n\n\n<p>O sambista Xande de Pilares volta a se apresentar em Sorocaba no dia 1\u00ba de novembro, quarta-feira, v\u00e9spera de feriado, no Clube de Campo Sorocaba. O evento, que ser\u00e1 100% open bar, contar\u00e1 com palco 360 graus, montado no centro do sal\u00e3o do clube. O show de abertura fica por conta da banda \u201cSe Quis\u00e9\u201d.<\/p>\n\n\n\n<p>\u201cA ideia de montar o palco no centro do recinto \u00e9 deixar o artista ainda mais perto do p\u00fablico. Tivemos experi\u00eancias maravilhosas em eventos com a mesma formata\u00e7\u00e3o na cidade\u201d, revela o produtor do evento.<\/p>\n\n\n\n<p>No repert\u00f3rio, hits do grupo Revela\u00e7\u00e3o, como \u2018Deixa Acontecer\u2019 e \u2018T\u00e1 Escrito\u2019, sucessos da carreira, como \u2018S\u00f3 Depois\u2019 e \u2018Minha Paz \u00e9 Voc\u00ea\u2019, al\u00e9m das novas faixas do projeto \u201cXande Canta Caetano\u201d, lan\u00e7ado neste ano nas plataformas digitais.<\/p>\n\n\n\n<p>Os ingressos para a apresenta\u00e7\u00e3o est\u00e3o \u00e0 venda, custam a partir de R$80 e podem ser adquiridos atrav\u00e9s do site <a href=\"http:\/\/guicheweb.com.br\">guicheweb.com.br<\/a> ou na Academia Viva Max, em Sorocaba. O Clube de Campo fica na Av. Engenheiro Carlos Reinaldo Mendes, 1.761, no Alto da Boa Vista. A classifica\u00e7\u00e3o et\u00e1ria \u00e9 18 anos. Mais informa\u00e7\u00f5es pelo telefone (15) 9 9797-5760.<\/p>\n\n\n\n<p><strong>Servi\u00e7o:<br><\/strong>Xande de Pilares em Sorocaba<br>Dia 1\u00ba de novembro, quarta-feira, v\u00e9spera de feriado<br>Local: Clube de Campo Sorocaba &#8211; Av. Eng. Carlos Reinaldo Mendes, 1.761, Alto da Boa Vista<br>Ingressos: a partir de R$80<br>Vendas: <a href=\"http:\/\/guicheweb.com.br\">guicheweb.com.br<\/a> | Academia Viva Max<br>Classifica\u00e7\u00e3o et\u00e1ria: 18 anos<br>Mais informa\u00e7\u00f5es: (15) 9 9797-5760<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apresenta\u00e7\u00e3o ser\u00e1 em novembro, no Clube de Campo, em evento 100% Open Bar.<\/p>\n","protected":false},"author":1,"featured_media":133895,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[166],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sambista Xande de Pilares anuncia show em Sorocaba<\/title>\n<meta name=\"description\" content=\"Apresenta\u00e7\u00e3o ser\u00e1 em novembro, no Clube de Campo, em evento 100% Open Bar.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalperiscopio.com.br\/site\/sambista-xande-de-pilares-anuncia-show-em-sorocaba\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sambista Xande de Pilares anuncia show em Sorocaba\" \/>\n<meta property=\"og:description\" content=\"Apresenta\u00e7\u00e3o ser\u00e1 em novembro, no Clube de Campo, em evento 100% Open Bar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalperiscopio.com.br\/site\/sambista-xande-de-pilares-anuncia-show-em-sorocaba\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal Perisc\u00f3pio | Jornal do Povo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornalperiscopioitu\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-31T21:10:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-31T21:10:50+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2023\/08\/xande-pilares-1280x720-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornal Perisc\u00f3pio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal Perisc\u00f3pio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/sambista-xande-de-pilares-anuncia-show-em-sorocaba\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/sambista-xande-de-pilares-anuncia-show-em-sorocaba\/\"},\"author\":{\"name\":\"Jornal Perisc\u00f3pio\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/person\/509eaa6e74ff99fb48058b4547d055d7\"},\"headline\":\"Sambista Xande de Pilares anuncia show em Sorocaba\",\"datePublished\":\"2023-08-31T21:10:33+00:00\",\"dateModified\":\"2023-08-31T21:10:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/sambista-xande-de-pilares-anuncia-show-em-sorocaba\/\"},\"wordCount\":246,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#organization\"},\"articleSection\":[\"Agenda\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/jornalperiscopio.com.br\/site\/sambista-xande-de-pilares-anuncia-show-em-sorocaba\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/sambista-xande-de-pilares-anuncia-show-em-sorocaba\/\",\"url\":\"https:\/\/jornalperiscopio.com.br\/site\/sambista-xande-de-pilares-anuncia-show-em-sorocaba\/\",\"name\":\"Sambista Xande de Pilares anuncia show em Sorocaba\",\"isPartOf\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#website\"},\"datePublished\":\"2023-08-31T21:10:33+00:00\",\"dateModified\":\"2023-08-31T21:10:50+00:00\",\"description\":\"Apresenta\u00e7\u00e3o ser\u00e1 em novembro, no Clube de Campo, em evento 100% Open Bar.\",\"breadcrumb\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/sambista-xande-de-pilares-anuncia-show-em-sorocaba\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/jornalperiscopio.com.br\/site\/sambista-xande-de-pilares-anuncia-show-em-sorocaba\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/sambista-xande-de-pilares-anuncia-show-em-sorocaba\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/jornalperiscopio.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sambista Xande de Pilares anuncia show em Sorocaba\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#website\",\"url\":\"https:\/\/jornalperiscopio.com.br\/site\/\",\"name\":\"Jornal Perisc\u00f3pio | Jornal do Povo\",\"description\":\"Jornal Perisc\u00f3pio\",\"publisher\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/jornalperiscopio.com.br\/site\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#organization\",\"name\":\"Jornal Perisc\u00f3pio\",\"url\":\"https:\/\/jornalperiscopio.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2017\/01\/cropped-cropped-logo_Jornal_Periscopio-2.png\",\"contentUrl\":\"http:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2017\/01\/cropped-cropped-logo_Jornal_Periscopio-2.png\",\"width\":420,\"height\":106,\"caption\":\"Jornal Perisc\u00f3pio\"},\"image\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/jornalperiscopioitu\/\",\"http:\/\/www.instagram.com\/jornalperiscopio\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/person\/509eaa6e74ff99fb48058b4547d055d7\",\"name\":\"Jornal Perisc\u00f3pio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7fd60e6256514f9f6bac0d31eb9382e6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7fd60e6256514f9f6bac0d31eb9382e6?s=96&d=mm&r=g\",\"caption\":\"Jornal Perisc\u00f3pio\"},\"url\":\"https:\/\/jornalperiscopio.com.br\/site\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sambista Xande de Pilares anuncia show em Sorocaba","description":"Apresenta\u00e7\u00e3o ser\u00e1 em novembro, no Clube de Campo, em evento 100% Open Bar.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalperiscopio.com.br\/site\/sambista-xande-de-pilares-anuncia-show-em-sorocaba\/","og_locale":"pt_BR","og_type":"article","og_title":"Sambista Xande de Pilares anuncia show em Sorocaba","og_description":"Apresenta\u00e7\u00e3o ser\u00e1 em novembro, no Clube de Campo, em evento 100% Open Bar.","og_url":"https:\/\/jornalperiscopio.com.br\/site\/sambista-xande-de-pilares-anuncia-show-em-sorocaba\/","og_site_name":"Jornal Perisc\u00f3pio | Jornal do Povo","article_publisher":"https:\/\/www.facebook.com\/jornalperiscopioitu\/","article_published_time":"2023-08-31T21:10:33+00:00","article_modified_time":"2023-08-31T21:10:50+00:00","og_image":[{"width":1280,"height":720,"url":"http:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2023\/08\/xande-pilares-1280x720-1.jpg","type":"image\/jpeg"}],"author":"Jornal Perisc\u00f3pio","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jornal Perisc\u00f3pio","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalperiscopio.com.br\/site\/sambista-xande-de-pilares-anuncia-show-em-sorocaba\/#article","isPartOf":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/sambista-xande-de-pilares-anuncia-show-em-sorocaba\/"},"author":{"name":"Jornal Perisc\u00f3pio","@id":"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/person\/509eaa6e74ff99fb48058b4547d055d7"},"headline":"Sambista Xande de Pilares anuncia show em Sorocaba","datePublished":"2023-08-31T21:10:33+00:00","dateModified":"2023-08-31T21:10:50+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/sambista-xande-de-pilares-anuncia-show-em-sorocaba\/"},"wordCount":246,"commentCount":0,"publisher":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/#organization"},"articleSection":["Agenda"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalperiscopio.com.br\/site\/sambista-xande-de-pilares-anuncia-show-em-sorocaba\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalperiscopio.com.br\/site\/sambista-xande-de-pilares-anuncia-show-em-sorocaba\/","url":"https:\/\/jornalperiscopio.com.br\/site\/sambista-xande-de-pilares-anuncia-show-em-sorocaba\/","name":"Sambista Xande de Pilares anuncia show em Sorocaba","isPartOf":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/#website"},"datePublished":"2023-08-31T21:10:33+00:00","dateModified":"2023-08-31T21:10:50+00:00","description":"Apresenta\u00e7\u00e3o ser\u00e1 em novembro, no Clube de Campo, em evento 100% Open Bar.","breadcrumb":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/sambista-xande-de-pilares-anuncia-show-em-sorocaba\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalperiscopio.com.br\/site\/sambista-xande-de-pilares-anuncia-show-em-sorocaba\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/jornalperiscopio.com.br\/site\/sambista-xande-de-pilares-anuncia-show-em-sorocaba\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jornalperiscopio.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Sambista Xande de Pilares anuncia show em Sorocaba"}]},{"@type":"WebSite","@id":"https:\/\/jornalperiscopio.com.br\/site\/#website","url":"https:\/\/jornalperiscopio.com.br\/site\/","name":"Jornal Perisc\u00f3pio | Jornal do Povo","description":"Jornal Perisc\u00f3pio","publisher":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornalperiscopio.com.br\/site\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jornalperiscopio.com.br\/site\/#organization","name":"Jornal Perisc\u00f3pio","url":"https:\/\/jornalperiscopio.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/logo\/image\/","url":"http:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2017\/01\/cropped-cropped-logo_Jornal_Periscopio-2.png","contentUrl":"http:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2017\/01\/cropped-cropped-logo_Jornal_Periscopio-2.png","width":420,"height":106,"caption":"Jornal Perisc\u00f3pio"},"image":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jornalperiscopioitu\/","http:\/\/www.instagram.com\/jornalperiscopio"]},{"@type":"Person","@id":"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/person\/509eaa6e74ff99fb48058b4547d055d7","name":"Jornal Perisc\u00f3pio","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7fd60e6256514f9f6bac0d31eb9382e6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7fd60e6256514f9f6bac0d31eb9382e6?s=96&d=mm&r=g","caption":"Jornal Perisc\u00f3pio"},"url":"https:\/\/jornalperiscopio.com.br\/site\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/posts\/133894"}],"collection":[{"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/comments?post=133894"}],"version-history":[{"count":3,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/posts\/133894\/revisions"}],"predecessor-version":[{"id":133898,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/posts\/133894\/revisions\/133898"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/media\/133895"}],"wp:attachment":[{"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/media?parent=133894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/categories?post=133894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/tags?post=133894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}