﻿{"id":155821,"date":"2026-05-13T14:51:39","date_gmt":"2026-05-13T17:51:39","guid":{"rendered":"https:\/\/jornalperiscopio.com.br\/site\/?p=155821"},"modified":"2026-05-13T14:51:46","modified_gmt":"2026-05-13T17:51:46","slug":"acadil-celebra-centenario-do-prof-cid-rocha-neste-sabado","status":"publish","type":"post","link":"https:\/\/jornalperiscopio.com.br\/site\/acadil-celebra-centenario-do-prof-cid-rocha-neste-sabado\/","title":{"rendered":"ACADIL celebra centen\u00e1rio do Prof. Cid Rocha neste s\u00e1bado"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"960\" src=\"http:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2023\/07\/ACADIL.jpg\" alt=\"\" class=\"wp-image-133170\" srcset=\"https:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2023\/07\/ACADIL.jpg 1280w, https:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2023\/07\/ACADIL-667x500.jpg 667w, https:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2023\/07\/ACADIL-768x576.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><figcaption class=\"wp-element-caption\"><strong><sup>Evento ser\u00e1 realizado no Espa\u00e7o Euclydes Marins e Dias, \u00e0 Rua Luiz Vaz de Cam\u00f5es, 157, Jardim Conven\u00e7\u00e3o (Foto: Arquivo)<\/sup><\/strong><\/figcaption><\/figure>\n\n\n\n<p>No pr\u00f3ximo s\u00e1bado (16), a partir das 10h, a ACADIL (Academia Ituana de Letras) realizar\u00e1 uma Reuni\u00e3o Festiva para celebrar o primeiro centen\u00e1rio de nascimento do Prof. Cid Rocha (1926 \u2013 1988). Patrono da Cadeira 02, o jornalista e professor ituano foi muito atuante na imprensa local, pol\u00eamico articulista, prosador e poeta. Deixou uma quantidade expressiva de originais que est\u00e3o sendo transferidos, pelos seus filhos, \u00e0 ACADIL. O Prof. Cid Rocha foi tamb\u00e9m professor em diversas escolas ituanas, aposentando-se do magist\u00e9rio em 1981.&nbsp;<\/p>\n\n\n\n<p>Na ocasi\u00e3o haver\u00e1 o lan\u00e7amento do volume 10 da cole\u00e7\u00e3o Patronos da ACADIL, com mat\u00e9rias do Prof. Cid Rocha, tra\u00e7os biogr\u00e1ficos e coment\u00e1rios \u00e0 sua obra. Participar\u00e3o do evento, fazendo uso da palavra, acad\u00eamicos, familiares, estudantes e professores da EMEF Prof. Cid Rocha.&nbsp;<\/p>\n\n\n\n<p>A segunda parte da reuni\u00e3o ter\u00e1 o lan\u00e7amento do projeto Mem\u00f3rias Afro-Ituanas, uma parceria com o Instituto Cultural de Itu, Museu da M\u00fasica \u2013 Itu, Centro Ituano de Letras e Artes, Biblioteca P\u00fablica Prof. Olavo Valente e Coordenadoria de Promo\u00e7\u00e3o da Igualdade Racial de Itu. A comunica\u00e7\u00e3o estar\u00e1 a cargo do Prof. Michel de Oliveira, historiador, vereador de Salto e pesquisador no projeto Biografias Afro-Saltenses, com o tema \u201cBiografias Hist\u00f3ricas: Novos Olhares sobre o Silenciamento da Mem\u00f3ria Negra\u201d.<\/p>\n\n\n\n<p>O evento, que est\u00e1 relacionado tamb\u00e9m \u00e0 comemora\u00e7\u00e3o do centen\u00e1rio de nascimento do ge\u00f3grafo Milton Santos, tem entrada franca e ser\u00e1 realizado no Espa\u00e7o Euclydes Marins e Dias, \u00e0 Rua Luiz Vaz de Cam\u00f5es, 157, Jardim Conven\u00e7\u00e3o, em Itu, sede da ACADIL.&nbsp;&nbsp;<\/p>\n\n\n\n<p>A Academia Ituana de Letras \u00e9 uma associa\u00e7\u00e3o que re\u00fane 37 escritores de diversas \u00e1reas do saber, atuantes atrav\u00e9s da prosa e do verso. Publica anualmente a sua revista liter\u00e1ria al\u00e9m de outras edi\u00e7\u00f5es prestigiando seus patronos e a obra dos acad\u00eamicos.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Reuni\u00e3o discutir\u00e1 tamb\u00e9m Mem\u00f3rias Afro-Ituanas, com apresenta\u00e7\u00e3o do Prof. Michel de Oliveira.<\/p>\n","protected":false},"author":1,"featured_media":133170,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[10,282],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ACADIL celebra centen\u00e1rio do Prof. Cid Rocha neste s\u00e1bado<\/title>\n<meta name=\"description\" content=\"Reuni\u00e3o discutir\u00e1 tamb\u00e9m Mem\u00f3rias Afro-Ituanas, com apresenta\u00e7\u00e3o do Prof. Michel de Oliveira.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalperiscopio.com.br\/site\/acadil-celebra-centenario-do-prof-cid-rocha-neste-sabado\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ACADIL celebra centen\u00e1rio do Prof. Cid Rocha neste s\u00e1bado\" \/>\n<meta property=\"og:description\" content=\"Reuni\u00e3o discutir\u00e1 tamb\u00e9m Mem\u00f3rias Afro-Ituanas, com apresenta\u00e7\u00e3o do Prof. Michel de Oliveira.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalperiscopio.com.br\/site\/acadil-celebra-centenario-do-prof-cid-rocha-neste-sabado\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal Perisc\u00f3pio | Jornal do Povo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornalperiscopioitu\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T17:51:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T17:51:46+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2023\/07\/ACADIL.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornal Perisc\u00f3pio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal Perisc\u00f3pio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/acadil-celebra-centenario-do-prof-cid-rocha-neste-sabado\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/acadil-celebra-centenario-do-prof-cid-rocha-neste-sabado\/\"},\"author\":{\"name\":\"Jornal Perisc\u00f3pio\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/person\/509eaa6e74ff99fb48058b4547d055d7\"},\"headline\":\"ACADIL celebra centen\u00e1rio do Prof. Cid Rocha neste s\u00e1bado\",\"datePublished\":\"2026-05-13T17:51:39+00:00\",\"dateModified\":\"2026-05-13T17:51:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/acadil-celebra-centenario-do-prof-cid-rocha-neste-sabado\/\"},\"wordCount\":350,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#organization\"},\"articleSection\":[\"Cultura\",\"Destaques\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/jornalperiscopio.com.br\/site\/acadil-celebra-centenario-do-prof-cid-rocha-neste-sabado\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/acadil-celebra-centenario-do-prof-cid-rocha-neste-sabado\/\",\"url\":\"https:\/\/jornalperiscopio.com.br\/site\/acadil-celebra-centenario-do-prof-cid-rocha-neste-sabado\/\",\"name\":\"ACADIL celebra centen\u00e1rio do Prof. Cid Rocha neste s\u00e1bado\",\"isPartOf\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#website\"},\"datePublished\":\"2026-05-13T17:51:39+00:00\",\"dateModified\":\"2026-05-13T17:51:46+00:00\",\"description\":\"Reuni\u00e3o discutir\u00e1 tamb\u00e9m Mem\u00f3rias Afro-Ituanas, com apresenta\u00e7\u00e3o do Prof. Michel de Oliveira.\",\"breadcrumb\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/acadil-celebra-centenario-do-prof-cid-rocha-neste-sabado\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/jornalperiscopio.com.br\/site\/acadil-celebra-centenario-do-prof-cid-rocha-neste-sabado\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/acadil-celebra-centenario-do-prof-cid-rocha-neste-sabado\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/jornalperiscopio.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ACADIL celebra centen\u00e1rio do Prof. Cid Rocha neste s\u00e1bado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#website\",\"url\":\"https:\/\/jornalperiscopio.com.br\/site\/\",\"name\":\"Jornal Perisc\u00f3pio | Jornal do Povo\",\"description\":\"Jornal Perisc\u00f3pio\",\"publisher\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/jornalperiscopio.com.br\/site\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#organization\",\"name\":\"Jornal Perisc\u00f3pio\",\"url\":\"https:\/\/jornalperiscopio.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2017\/01\/cropped-cropped-logo_Jornal_Periscopio-2.png\",\"contentUrl\":\"http:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2017\/01\/cropped-cropped-logo_Jornal_Periscopio-2.png\",\"width\":420,\"height\":106,\"caption\":\"Jornal Perisc\u00f3pio\"},\"image\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/jornalperiscopioitu\/\",\"http:\/\/www.instagram.com\/jornalperiscopio\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/person\/509eaa6e74ff99fb48058b4547d055d7\",\"name\":\"Jornal Perisc\u00f3pio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7fd60e6256514f9f6bac0d31eb9382e6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7fd60e6256514f9f6bac0d31eb9382e6?s=96&d=mm&r=g\",\"caption\":\"Jornal Perisc\u00f3pio\"},\"url\":\"https:\/\/jornalperiscopio.com.br\/site\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ACADIL celebra centen\u00e1rio do Prof. Cid Rocha neste s\u00e1bado","description":"Reuni\u00e3o discutir\u00e1 tamb\u00e9m Mem\u00f3rias Afro-Ituanas, com apresenta\u00e7\u00e3o do Prof. Michel de Oliveira.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalperiscopio.com.br\/site\/acadil-celebra-centenario-do-prof-cid-rocha-neste-sabado\/","og_locale":"pt_BR","og_type":"article","og_title":"ACADIL celebra centen\u00e1rio do Prof. Cid Rocha neste s\u00e1bado","og_description":"Reuni\u00e3o discutir\u00e1 tamb\u00e9m Mem\u00f3rias Afro-Ituanas, com apresenta\u00e7\u00e3o do Prof. Michel de Oliveira.","og_url":"https:\/\/jornalperiscopio.com.br\/site\/acadil-celebra-centenario-do-prof-cid-rocha-neste-sabado\/","og_site_name":"Jornal Perisc\u00f3pio | Jornal do Povo","article_publisher":"https:\/\/www.facebook.com\/jornalperiscopioitu\/","article_published_time":"2026-05-13T17:51:39+00:00","article_modified_time":"2026-05-13T17:51:46+00:00","og_image":[{"width":1280,"height":960,"url":"http:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2023\/07\/ACADIL.jpg","type":"image\/jpeg"}],"author":"Jornal Perisc\u00f3pio","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jornal Perisc\u00f3pio","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalperiscopio.com.br\/site\/acadil-celebra-centenario-do-prof-cid-rocha-neste-sabado\/#article","isPartOf":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/acadil-celebra-centenario-do-prof-cid-rocha-neste-sabado\/"},"author":{"name":"Jornal Perisc\u00f3pio","@id":"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/person\/509eaa6e74ff99fb48058b4547d055d7"},"headline":"ACADIL celebra centen\u00e1rio do Prof. Cid Rocha neste s\u00e1bado","datePublished":"2026-05-13T17:51:39+00:00","dateModified":"2026-05-13T17:51:46+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/acadil-celebra-centenario-do-prof-cid-rocha-neste-sabado\/"},"wordCount":350,"commentCount":0,"publisher":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/#organization"},"articleSection":["Cultura","Destaques"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalperiscopio.com.br\/site\/acadil-celebra-centenario-do-prof-cid-rocha-neste-sabado\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalperiscopio.com.br\/site\/acadil-celebra-centenario-do-prof-cid-rocha-neste-sabado\/","url":"https:\/\/jornalperiscopio.com.br\/site\/acadil-celebra-centenario-do-prof-cid-rocha-neste-sabado\/","name":"ACADIL celebra centen\u00e1rio do Prof. Cid Rocha neste s\u00e1bado","isPartOf":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/#website"},"datePublished":"2026-05-13T17:51:39+00:00","dateModified":"2026-05-13T17:51:46+00:00","description":"Reuni\u00e3o discutir\u00e1 tamb\u00e9m Mem\u00f3rias Afro-Ituanas, com apresenta\u00e7\u00e3o do Prof. Michel de Oliveira.","breadcrumb":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/acadil-celebra-centenario-do-prof-cid-rocha-neste-sabado\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalperiscopio.com.br\/site\/acadil-celebra-centenario-do-prof-cid-rocha-neste-sabado\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/jornalperiscopio.com.br\/site\/acadil-celebra-centenario-do-prof-cid-rocha-neste-sabado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jornalperiscopio.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"ACADIL celebra centen\u00e1rio do Prof. Cid Rocha neste s\u00e1bado"}]},{"@type":"WebSite","@id":"https:\/\/jornalperiscopio.com.br\/site\/#website","url":"https:\/\/jornalperiscopio.com.br\/site\/","name":"Jornal Perisc\u00f3pio | Jornal do Povo","description":"Jornal Perisc\u00f3pio","publisher":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornalperiscopio.com.br\/site\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jornalperiscopio.com.br\/site\/#organization","name":"Jornal Perisc\u00f3pio","url":"https:\/\/jornalperiscopio.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/logo\/image\/","url":"http:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2017\/01\/cropped-cropped-logo_Jornal_Periscopio-2.png","contentUrl":"http:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2017\/01\/cropped-cropped-logo_Jornal_Periscopio-2.png","width":420,"height":106,"caption":"Jornal Perisc\u00f3pio"},"image":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jornalperiscopioitu\/","http:\/\/www.instagram.com\/jornalperiscopio"]},{"@type":"Person","@id":"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/person\/509eaa6e74ff99fb48058b4547d055d7","name":"Jornal Perisc\u00f3pio","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7fd60e6256514f9f6bac0d31eb9382e6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7fd60e6256514f9f6bac0d31eb9382e6?s=96&d=mm&r=g","caption":"Jornal Perisc\u00f3pio"},"url":"https:\/\/jornalperiscopio.com.br\/site\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/posts\/155821"}],"collection":[{"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/comments?post=155821"}],"version-history":[{"count":1,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/posts\/155821\/revisions"}],"predecessor-version":[{"id":155823,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/posts\/155821\/revisions\/155823"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/media\/133170"}],"wp:attachment":[{"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/media?parent=155821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/categories?post=155821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/tags?post=155821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}