﻿{"id":45300,"date":"2016-04-28T11:02:45","date_gmt":"2016-04-28T14:02:45","guid":{"rendered":"http:\/\/jornalperiscopio.com.br\/site\/?p=45300"},"modified":"2016-04-28T11:02:45","modified_gmt":"2016-04-28T14:02:45","slug":"ong-dentistas-do-bem-estara-no-cras-promai-nesta-quinta-feira","status":"publish","type":"post","link":"https:\/\/jornalperiscopio.com.br\/site\/ong-dentistas-do-bem-estara-no-cras-promai-nesta-quinta-feira\/","title":{"rendered":"ONG Dentistas do Bem estar\u00e1 no Cras Promai nesta quinta-feira"},"content":{"rendered":"<p style=\"text-align: justify;\">O Cras (Centro de Refer\u00eancia e Assist\u00eancia Social) Promai recebe hoje (28), das 9h \u00e0s 14h, o Doutor Garbes, da Ong Dentistas do Bem, para triagem de tratamento dent\u00e1rio gratuito de crian\u00e7as e adolescentes de 11 a 17 anos. As crian\u00e7as e adolescentes que passar\u00e3o pela triagem s\u00e3o de fam\u00edlias referenciadas no Cras e de baixa renda.<\/p>\n<p style=\"text-align: justify;\">Desta triagem ser\u00e3o contemplados aqueles que necessitam, com maior urg\u00eancia, de tratamento ou coloca\u00e7\u00e3o de aparelho ortod\u00f4ntico por problemas bucais graves. O acompanhamento dent\u00e1rio ser\u00e1 at\u00e9 que o paciente complete 18 anos, no consult\u00f3rio do pr\u00f3prio dentista volunt\u00e1rio.<\/p>\n<p style=\"text-align: justify;\">Projeto Dentista do Bem conta com volunt\u00e1rios espalhados por 1,5 mil munic\u00edpios brasileiros, 12 pa\u00edses da Am\u00e9rica Latina e em Portugal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Cras (Centro de Refer\u00eancia e Assist\u00eancia Social) Promai recebe hoje (28), das 9h \u00e0s 14h, o Doutor Garbes, da<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[2,14,48],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ONG Dentistas do Bem estar\u00e1 no Cras Promai nesta quinta-feira<\/title>\n<meta name=\"description\" content=\"O Cras (Centro de Refer\u00eancia e Assist\u00eancia Social) Promai recebe hoje (28), das 9h \u00e0s 14h, o Doutor Garbes, da Ong Dentistas do Bem, para triagem de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalperiscopio.com.br\/site\/ong-dentistas-do-bem-estara-no-cras-promai-nesta-quinta-feira\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ONG Dentistas do Bem estar\u00e1 no Cras Promai nesta quinta-feira\" \/>\n<meta property=\"og:description\" content=\"O Cras (Centro de Refer\u00eancia e Assist\u00eancia Social) Promai recebe hoje (28), das 9h \u00e0s 14h, o Doutor Garbes, da Ong Dentistas do Bem, para triagem de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalperiscopio.com.br\/site\/ong-dentistas-do-bem-estara-no-cras-promai-nesta-quinta-feira\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal Perisc\u00f3pio | Jornal do Povo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornalperiscopioitu\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-28T14:02:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2017\/01\/cropped-cropped-logo_Jornal_Periscopio-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"420\" \/>\n\t<meta property=\"og:image:height\" content=\"106\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Andr\u00e9 Roedel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andr\u00e9 Roedel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/ong-dentistas-do-bem-estara-no-cras-promai-nesta-quinta-feira\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/ong-dentistas-do-bem-estara-no-cras-promai-nesta-quinta-feira\/\"},\"author\":{\"name\":\"Andr\u00e9 Roedel\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/person\/3dae6b83a83e3a18e259f65640b2eb1f\"},\"headline\":\"ONG Dentistas do Bem estar\u00e1 no Cras Promai nesta quinta-feira\",\"datePublished\":\"2016-04-28T14:02:45+00:00\",\"dateModified\":\"2016-04-28T14:02:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/ong-dentistas-do-bem-estara-no-cras-promai-nesta-quinta-feira\/\"},\"wordCount\":140,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#organization\"},\"articleSection\":[\"Itu\",\"Sa\u00fade\",\"\u00daltimas Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/jornalperiscopio.com.br\/site\/ong-dentistas-do-bem-estara-no-cras-promai-nesta-quinta-feira\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/ong-dentistas-do-bem-estara-no-cras-promai-nesta-quinta-feira\/\",\"url\":\"https:\/\/jornalperiscopio.com.br\/site\/ong-dentistas-do-bem-estara-no-cras-promai-nesta-quinta-feira\/\",\"name\":\"ONG Dentistas do Bem estar\u00e1 no Cras Promai nesta quinta-feira\",\"isPartOf\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#website\"},\"datePublished\":\"2016-04-28T14:02:45+00:00\",\"dateModified\":\"2016-04-28T14:02:45+00:00\",\"description\":\"O Cras (Centro de Refer\u00eancia e Assist\u00eancia Social) Promai recebe hoje (28), das 9h \u00e0s 14h, o Doutor Garbes, da Ong Dentistas do Bem, para triagem de\",\"breadcrumb\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/ong-dentistas-do-bem-estara-no-cras-promai-nesta-quinta-feira\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/jornalperiscopio.com.br\/site\/ong-dentistas-do-bem-estara-no-cras-promai-nesta-quinta-feira\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/ong-dentistas-do-bem-estara-no-cras-promai-nesta-quinta-feira\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/jornalperiscopio.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ONG Dentistas do Bem estar\u00e1 no Cras Promai nesta quinta-feira\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#website\",\"url\":\"https:\/\/jornalperiscopio.com.br\/site\/\",\"name\":\"Jornal Perisc\u00f3pio | Jornal do Povo\",\"description\":\"Jornal Perisc\u00f3pio\",\"publisher\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/jornalperiscopio.com.br\/site\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#organization\",\"name\":\"Jornal Perisc\u00f3pio\",\"url\":\"https:\/\/jornalperiscopio.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2017\/01\/cropped-cropped-logo_Jornal_Periscopio-2.png\",\"contentUrl\":\"http:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2017\/01\/cropped-cropped-logo_Jornal_Periscopio-2.png\",\"width\":420,\"height\":106,\"caption\":\"Jornal Perisc\u00f3pio\"},\"image\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/jornalperiscopioitu\/\",\"http:\/\/www.instagram.com\/jornalperiscopio\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/person\/3dae6b83a83e3a18e259f65640b2eb1f\",\"name\":\"Andr\u00e9 Roedel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3a62a9ee5934bf7cd122a2cfa7a8b13a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3a62a9ee5934bf7cd122a2cfa7a8b13a?s=96&d=mm&r=g\",\"caption\":\"Andr\u00e9 Roedel\"},\"url\":\"https:\/\/jornalperiscopio.com.br\/site\/author\/andreroedel\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ONG Dentistas do Bem estar\u00e1 no Cras Promai nesta quinta-feira","description":"O Cras (Centro de Refer\u00eancia e Assist\u00eancia Social) Promai recebe hoje (28), das 9h \u00e0s 14h, o Doutor Garbes, da Ong Dentistas do Bem, para triagem de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalperiscopio.com.br\/site\/ong-dentistas-do-bem-estara-no-cras-promai-nesta-quinta-feira\/","og_locale":"pt_BR","og_type":"article","og_title":"ONG Dentistas do Bem estar\u00e1 no Cras Promai nesta quinta-feira","og_description":"O Cras (Centro de Refer\u00eancia e Assist\u00eancia Social) Promai recebe hoje (28), das 9h \u00e0s 14h, o Doutor Garbes, da Ong Dentistas do Bem, para triagem de","og_url":"https:\/\/jornalperiscopio.com.br\/site\/ong-dentistas-do-bem-estara-no-cras-promai-nesta-quinta-feira\/","og_site_name":"Jornal Perisc\u00f3pio | Jornal do Povo","article_publisher":"https:\/\/www.facebook.com\/jornalperiscopioitu\/","article_published_time":"2016-04-28T14:02:45+00:00","og_image":[{"width":420,"height":106,"url":"https:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2017\/01\/cropped-cropped-logo_Jornal_Periscopio-2.png","type":"image\/png"}],"author":"Andr\u00e9 Roedel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Andr\u00e9 Roedel","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalperiscopio.com.br\/site\/ong-dentistas-do-bem-estara-no-cras-promai-nesta-quinta-feira\/#article","isPartOf":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/ong-dentistas-do-bem-estara-no-cras-promai-nesta-quinta-feira\/"},"author":{"name":"Andr\u00e9 Roedel","@id":"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/person\/3dae6b83a83e3a18e259f65640b2eb1f"},"headline":"ONG Dentistas do Bem estar\u00e1 no Cras Promai nesta quinta-feira","datePublished":"2016-04-28T14:02:45+00:00","dateModified":"2016-04-28T14:02:45+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/ong-dentistas-do-bem-estara-no-cras-promai-nesta-quinta-feira\/"},"wordCount":140,"commentCount":1,"publisher":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/#organization"},"articleSection":["Itu","Sa\u00fade","\u00daltimas Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalperiscopio.com.br\/site\/ong-dentistas-do-bem-estara-no-cras-promai-nesta-quinta-feira\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalperiscopio.com.br\/site\/ong-dentistas-do-bem-estara-no-cras-promai-nesta-quinta-feira\/","url":"https:\/\/jornalperiscopio.com.br\/site\/ong-dentistas-do-bem-estara-no-cras-promai-nesta-quinta-feira\/","name":"ONG Dentistas do Bem estar\u00e1 no Cras Promai nesta quinta-feira","isPartOf":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/#website"},"datePublished":"2016-04-28T14:02:45+00:00","dateModified":"2016-04-28T14:02:45+00:00","description":"O Cras (Centro de Refer\u00eancia e Assist\u00eancia Social) Promai recebe hoje (28), das 9h \u00e0s 14h, o Doutor Garbes, da Ong Dentistas do Bem, para triagem de","breadcrumb":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/ong-dentistas-do-bem-estara-no-cras-promai-nesta-quinta-feira\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalperiscopio.com.br\/site\/ong-dentistas-do-bem-estara-no-cras-promai-nesta-quinta-feira\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/jornalperiscopio.com.br\/site\/ong-dentistas-do-bem-estara-no-cras-promai-nesta-quinta-feira\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jornalperiscopio.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"ONG Dentistas do Bem estar\u00e1 no Cras Promai nesta quinta-feira"}]},{"@type":"WebSite","@id":"https:\/\/jornalperiscopio.com.br\/site\/#website","url":"https:\/\/jornalperiscopio.com.br\/site\/","name":"Jornal Perisc\u00f3pio | Jornal do Povo","description":"Jornal Perisc\u00f3pio","publisher":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornalperiscopio.com.br\/site\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jornalperiscopio.com.br\/site\/#organization","name":"Jornal Perisc\u00f3pio","url":"https:\/\/jornalperiscopio.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/logo\/image\/","url":"http:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2017\/01\/cropped-cropped-logo_Jornal_Periscopio-2.png","contentUrl":"http:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2017\/01\/cropped-cropped-logo_Jornal_Periscopio-2.png","width":420,"height":106,"caption":"Jornal Perisc\u00f3pio"},"image":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jornalperiscopioitu\/","http:\/\/www.instagram.com\/jornalperiscopio"]},{"@type":"Person","@id":"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/person\/3dae6b83a83e3a18e259f65640b2eb1f","name":"Andr\u00e9 Roedel","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3a62a9ee5934bf7cd122a2cfa7a8b13a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3a62a9ee5934bf7cd122a2cfa7a8b13a?s=96&d=mm&r=g","caption":"Andr\u00e9 Roedel"},"url":"https:\/\/jornalperiscopio.com.br\/site\/author\/andreroedel\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/posts\/45300"}],"collection":[{"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/comments?post=45300"}],"version-history":[{"count":0,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/posts\/45300\/revisions"}],"wp:attachment":[{"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/media?parent=45300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/categories?post=45300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/tags?post=45300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}