﻿{"id":92052,"date":"2018-09-15T10:55:10","date_gmt":"2018-09-15T13:55:10","guid":{"rendered":"http:\/\/jornalperiscopio.com.br\/site\/?p=92052"},"modified":"2018-09-15T10:55:10","modified_gmt":"2018-09-15T13:55:10","slug":"campanha-natal-gigante-acii-ja-e-sucesso-no-comercio-local","status":"publish","type":"post","link":"https:\/\/jornalperiscopio.com.br\/site\/campanha-natal-gigante-acii-ja-e-sucesso-no-comercio-local\/","title":{"rendered":"Campanha \u201cNatal Gigante ACII\u201d j\u00e1 \u00e9 sucesso no com\u00e9rcio local"},"content":{"rendered":"<p><strong>\u00a0<\/strong><em>A Associa\u00e7\u00e3o Comercial e Industrial de Itu convida a todos os comerciantes de Itu para a a\u00e7\u00e3o. Saiba como aderir \u00e0 a\u00e7\u00e3o in\u00e9dita<\/em><\/p>\n<p><strong>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-92055\" src=\"http:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2018\/09\/natal-gigante.gif\" alt=\"\" width=\"800\" height=\"455\" \/><\/strong><\/p>\n<p>Tiveram in\u00edcio no dia 28 de agosto as ades\u00f5es \u00e0 Campanha \u201cNatal Gigante ACII\u201d, que ir\u00e1 sortear um autom\u00f3vel 0 km, pela Loteria Federal, e mais 200 vale-compras instant\u00e2neos no valor de R$ 50 (cinquenta reais).<\/p>\n<p>Esta \u00e9 mais uma das a\u00e7\u00f5es que a Associa\u00e7\u00e3o Comercial e Industrial de Itu (ACII) est\u00e1 promovendo com a finalidade de alavancar as vendas do com\u00e9rcio local, com vantagens para os clientes. A Campanha ter\u00e1 in\u00edcio no dia 26 de novembro com t\u00e9rmino em 31 de dezembro de 2018, com sorteio pela Loteria Federal no dia 12 de janeiro de 2019.<\/p>\n<p>O presidente da ACII, Rafaello Lorenzon, convida o com\u00e9rcio local para participar desta a\u00e7\u00e3o, adquirindo os kits (bronze, prata, ouro ou diamante) que dar\u00e3o a oportunidade de participar deste sorteio \u2013 a regra principal para a participa\u00e7\u00e3o \u00e9 ser associado.<\/p>\n<p>&#8220;Voc\u00ea comerciante que n\u00e3o \u00e9 associado, ainda d\u00e1 tempo de se associar e participar da Campanha. Para mais informa\u00e7\u00f5es, basta ligar, que encaminharemos nosso representante comercial at\u00e9 seu estabelecimento\u201d, disse Rafaello.<\/p>\n<p>Est\u00e1 \u00e9 a primeira vez que a Associa\u00e7\u00e3o Comercial promove uma campanha deste porte, e agradou aos associados que aderiram com muita anima\u00e7\u00e3o e grandes expectativas para um final de ano com boas vendas. A campanha ter\u00e1 um site para cadastramento dos cupons\/seladinhas, regulamento e informa\u00e7\u00f5es dos estabelecimentos que estar\u00e3o participando.<\/p>\n<p>Toda essa a\u00e7\u00e3o ser\u00e1 divulgada em v\u00e1rios ve\u00edculos de comunica\u00e7\u00e3o, al\u00e9m de outdoors, cartazes e m\u00eddias sociais. \u201c\u00c9 uma \u00f3tima oportunidade para divulgar seu com\u00e9rcio, com valores pequenos e com grande visibilidade em toda a cidade. Quanto maior o n\u00famero de participantes, maior ser\u00e1 o sucesso desta campanha que j\u00e1 iniciou gigante\u201d, finalizou Rafaello.<\/p>\n<p>Os estabelecimentos comerciais interessados em aderir \u00e0 campanha devem entrar em contato com a ACII pelo telefone (11) 4013-8833.<\/p>\n<blockquote><p>TABELA<\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"150\">KIT BRONZE<\/td>\n<td width=\"150\">KIT PRATA<\/td>\n<td width=\"150\">KIT OURO<\/td>\n<td width=\"150\">KIT DIAMANTE<\/td>\n<\/tr>\n<tr>\n<td width=\"150\">500 cupons<\/td>\n<td width=\"150\">1.000 cupons<\/td>\n<td width=\"150\">1.500 cupons<\/td>\n<td width=\"150\">5.000 cupons<\/td>\n<\/tr>\n<tr>\n<td width=\"150\">2 vale-compras<\/td>\n<td width=\"150\">4 vale-compras<\/td>\n<td width=\"150\">6 vale-compras<\/td>\n<td width=\"150\">12 vale-compras<\/td>\n<\/tr>\n<tr>\n<td width=\"150\">R$ 400<\/td>\n<td width=\"150\">R$ 700<\/td>\n<td width=\"150\">R$ 1.000<\/td>\n<td width=\"150\">R$ 2.500<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/blockquote>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Associa\u00e7\u00e3o Comercial e Industrial de Itu convida a todos os comerciantes de Itu para a a\u00e7\u00e3o. Saiba como aderir \u00e0 a\u00e7\u00e3o in\u00e9dita<\/p>\n","protected":false},"author":1,"featured_media":92055,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[6,33],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Campanha \u201cNatal Gigante ACII\u201d j\u00e1 \u00e9 sucesso no com\u00e9rcio local<\/title>\n<meta name=\"description\" content=\"A Associa\u00e7\u00e3o Comercial e Industrial de Itu convida a todos os comerciantes de Itu para a a\u00e7\u00e3o. Saiba como aderir \u00e0 a\u00e7\u00e3o in\u00e9dita\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalperiscopio.com.br\/site\/campanha-natal-gigante-acii-ja-e-sucesso-no-comercio-local\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campanha \u201cNatal Gigante ACII\u201d j\u00e1 \u00e9 sucesso no com\u00e9rcio local\" \/>\n<meta property=\"og:description\" content=\"A Associa\u00e7\u00e3o Comercial e Industrial de Itu convida a todos os comerciantes de Itu para a a\u00e7\u00e3o. Saiba como aderir \u00e0 a\u00e7\u00e3o in\u00e9dita\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalperiscopio.com.br\/site\/campanha-natal-gigante-acii-ja-e-sucesso-no-comercio-local\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal Perisc\u00f3pio | Jornal do Povo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornalperiscopioitu\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-15T13:55:10+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2018\/09\/natal-gigante.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"455\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"Jornal Perisc\u00f3pio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal Perisc\u00f3pio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/campanha-natal-gigante-acii-ja-e-sucesso-no-comercio-local\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/campanha-natal-gigante-acii-ja-e-sucesso-no-comercio-local\/\"},\"author\":{\"name\":\"Jornal Perisc\u00f3pio\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/person\/509eaa6e74ff99fb48058b4547d055d7\"},\"headline\":\"Campanha \u201cNatal Gigante ACII\u201d j\u00e1 \u00e9 sucesso no com\u00e9rcio local\",\"datePublished\":\"2018-09-15T13:55:10+00:00\",\"dateModified\":\"2018-09-15T13:55:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/campanha-natal-gigante-acii-ja-e-sucesso-no-comercio-local\/\"},\"wordCount\":360,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#organization\"},\"articleSection\":[\"Colunas\",\"Neg\u00f3cios\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/jornalperiscopio.com.br\/site\/campanha-natal-gigante-acii-ja-e-sucesso-no-comercio-local\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/campanha-natal-gigante-acii-ja-e-sucesso-no-comercio-local\/\",\"url\":\"https:\/\/jornalperiscopio.com.br\/site\/campanha-natal-gigante-acii-ja-e-sucesso-no-comercio-local\/\",\"name\":\"Campanha \u201cNatal Gigante ACII\u201d j\u00e1 \u00e9 sucesso no com\u00e9rcio local\",\"isPartOf\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#website\"},\"datePublished\":\"2018-09-15T13:55:10+00:00\",\"dateModified\":\"2018-09-15T13:55:10+00:00\",\"description\":\"A Associa\u00e7\u00e3o Comercial e Industrial de Itu convida a todos os comerciantes de Itu para a a\u00e7\u00e3o. Saiba como aderir \u00e0 a\u00e7\u00e3o in\u00e9dita\",\"breadcrumb\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/campanha-natal-gigante-acii-ja-e-sucesso-no-comercio-local\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/jornalperiscopio.com.br\/site\/campanha-natal-gigante-acii-ja-e-sucesso-no-comercio-local\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/campanha-natal-gigante-acii-ja-e-sucesso-no-comercio-local\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/jornalperiscopio.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campanha \u201cNatal Gigante ACII\u201d j\u00e1 \u00e9 sucesso no com\u00e9rcio local\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#website\",\"url\":\"https:\/\/jornalperiscopio.com.br\/site\/\",\"name\":\"Jornal Perisc\u00f3pio | Jornal do Povo\",\"description\":\"Jornal Perisc\u00f3pio\",\"publisher\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/jornalperiscopio.com.br\/site\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#organization\",\"name\":\"Jornal Perisc\u00f3pio\",\"url\":\"https:\/\/jornalperiscopio.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2017\/01\/cropped-cropped-logo_Jornal_Periscopio-2.png\",\"contentUrl\":\"http:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2017\/01\/cropped-cropped-logo_Jornal_Periscopio-2.png\",\"width\":420,\"height\":106,\"caption\":\"Jornal Perisc\u00f3pio\"},\"image\":{\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/jornalperiscopioitu\/\",\"http:\/\/www.instagram.com\/jornalperiscopio\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/person\/509eaa6e74ff99fb48058b4547d055d7\",\"name\":\"Jornal Perisc\u00f3pio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7fd60e6256514f9f6bac0d31eb9382e6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7fd60e6256514f9f6bac0d31eb9382e6?s=96&d=mm&r=g\",\"caption\":\"Jornal Perisc\u00f3pio\"},\"url\":\"https:\/\/jornalperiscopio.com.br\/site\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Campanha \u201cNatal Gigante ACII\u201d j\u00e1 \u00e9 sucesso no com\u00e9rcio local","description":"A Associa\u00e7\u00e3o Comercial e Industrial de Itu convida a todos os comerciantes de Itu para a a\u00e7\u00e3o. Saiba como aderir \u00e0 a\u00e7\u00e3o in\u00e9dita","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalperiscopio.com.br\/site\/campanha-natal-gigante-acii-ja-e-sucesso-no-comercio-local\/","og_locale":"pt_BR","og_type":"article","og_title":"Campanha \u201cNatal Gigante ACII\u201d j\u00e1 \u00e9 sucesso no com\u00e9rcio local","og_description":"A Associa\u00e7\u00e3o Comercial e Industrial de Itu convida a todos os comerciantes de Itu para a a\u00e7\u00e3o. Saiba como aderir \u00e0 a\u00e7\u00e3o in\u00e9dita","og_url":"https:\/\/jornalperiscopio.com.br\/site\/campanha-natal-gigante-acii-ja-e-sucesso-no-comercio-local\/","og_site_name":"Jornal Perisc\u00f3pio | Jornal do Povo","article_publisher":"https:\/\/www.facebook.com\/jornalperiscopioitu\/","article_published_time":"2018-09-15T13:55:10+00:00","og_image":[{"width":800,"height":455,"url":"http:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2018\/09\/natal-gigante.gif","type":"image\/gif"}],"author":"Jornal Perisc\u00f3pio","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jornal Perisc\u00f3pio","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalperiscopio.com.br\/site\/campanha-natal-gigante-acii-ja-e-sucesso-no-comercio-local\/#article","isPartOf":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/campanha-natal-gigante-acii-ja-e-sucesso-no-comercio-local\/"},"author":{"name":"Jornal Perisc\u00f3pio","@id":"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/person\/509eaa6e74ff99fb48058b4547d055d7"},"headline":"Campanha \u201cNatal Gigante ACII\u201d j\u00e1 \u00e9 sucesso no com\u00e9rcio local","datePublished":"2018-09-15T13:55:10+00:00","dateModified":"2018-09-15T13:55:10+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/campanha-natal-gigante-acii-ja-e-sucesso-no-comercio-local\/"},"wordCount":360,"commentCount":3,"publisher":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/#organization"},"articleSection":["Colunas","Neg\u00f3cios"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalperiscopio.com.br\/site\/campanha-natal-gigante-acii-ja-e-sucesso-no-comercio-local\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalperiscopio.com.br\/site\/campanha-natal-gigante-acii-ja-e-sucesso-no-comercio-local\/","url":"https:\/\/jornalperiscopio.com.br\/site\/campanha-natal-gigante-acii-ja-e-sucesso-no-comercio-local\/","name":"Campanha \u201cNatal Gigante ACII\u201d j\u00e1 \u00e9 sucesso no com\u00e9rcio local","isPartOf":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/#website"},"datePublished":"2018-09-15T13:55:10+00:00","dateModified":"2018-09-15T13:55:10+00:00","description":"A Associa\u00e7\u00e3o Comercial e Industrial de Itu convida a todos os comerciantes de Itu para a a\u00e7\u00e3o. Saiba como aderir \u00e0 a\u00e7\u00e3o in\u00e9dita","breadcrumb":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/campanha-natal-gigante-acii-ja-e-sucesso-no-comercio-local\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalperiscopio.com.br\/site\/campanha-natal-gigante-acii-ja-e-sucesso-no-comercio-local\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/jornalperiscopio.com.br\/site\/campanha-natal-gigante-acii-ja-e-sucesso-no-comercio-local\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jornalperiscopio.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Campanha \u201cNatal Gigante ACII\u201d j\u00e1 \u00e9 sucesso no com\u00e9rcio local"}]},{"@type":"WebSite","@id":"https:\/\/jornalperiscopio.com.br\/site\/#website","url":"https:\/\/jornalperiscopio.com.br\/site\/","name":"Jornal Perisc\u00f3pio | Jornal do Povo","description":"Jornal Perisc\u00f3pio","publisher":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornalperiscopio.com.br\/site\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jornalperiscopio.com.br\/site\/#organization","name":"Jornal Perisc\u00f3pio","url":"https:\/\/jornalperiscopio.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/logo\/image\/","url":"http:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2017\/01\/cropped-cropped-logo_Jornal_Periscopio-2.png","contentUrl":"http:\/\/jornalperiscopio.com.br\/site\/wp-content\/uploads\/2017\/01\/cropped-cropped-logo_Jornal_Periscopio-2.png","width":420,"height":106,"caption":"Jornal Perisc\u00f3pio"},"image":{"@id":"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jornalperiscopioitu\/","http:\/\/www.instagram.com\/jornalperiscopio"]},{"@type":"Person","@id":"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/person\/509eaa6e74ff99fb48058b4547d055d7","name":"Jornal Perisc\u00f3pio","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalperiscopio.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7fd60e6256514f9f6bac0d31eb9382e6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7fd60e6256514f9f6bac0d31eb9382e6?s=96&d=mm&r=g","caption":"Jornal Perisc\u00f3pio"},"url":"https:\/\/jornalperiscopio.com.br\/site\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/posts\/92052"}],"collection":[{"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/comments?post=92052"}],"version-history":[{"count":2,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/posts\/92052\/revisions"}],"predecessor-version":[{"id":92056,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/posts\/92052\/revisions\/92056"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/media\/92055"}],"wp:attachment":[{"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/media?parent=92052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/categories?post=92052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalperiscopio.com.br\/site\/wp-json\/wp\/v2\/tags?post=92052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}